{"id":682,"date":"2025-11-23T22:18:23","date_gmt":"2025-11-23T22:18:23","guid":{"rendered":"https:\/\/boylefilmclub.ie\/?page_id=682"},"modified":"2025-11-23T23:16:59","modified_gmt":"2025-11-23T23:16:59","slug":"agm-2025","status":"publish","type":"page","link":"https:\/\/boylefilmclub.ie\/index.php\/agm-2025\/","title":{"rendered":"AGM 2025"},"content":{"rendered":"\n<p>Annual General Meeting 2025<\/p>\n\n\n\n<p>21 November &#8211; 7:30PM &#8211; Boyle Family Resource Center<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Attendance\n<ul class=\"wp-block-list\">\n<li>Maria Devine, Denise ODowd, Dyphna McNamara, Laura Hidalgo, Bevan DeQueker, Mick OMeara, Joe Treacy<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Club Committee Vote\n<ul class=\"wp-block-list\">\n<li>Chair: Laura Hidalgo<\/li>\n\n\n\n<li>Secretary: Mick O&#8217;Meara<\/li>\n\n\n\n<li>Treasurer: Bevan DeQueker<\/li>\n\n\n\n<li>General Advisor: Maria Devine<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Some Numbers\n<ul class=\"wp-block-list\">\n<li>Since September 2023<\/li>\n\n\n\n<li>49 movies screened, including:\n<ul class=\"wp-block-list\">\n<li>41 Feature-length<\/li>\n\n\n\n<li>8 Shorts<\/li>\n\n\n\n<li>33 Movie Nights for members<\/li>\n\n\n\n<li>14 Events including Boyle Arts Festival, Night&amp;Day Festival, Jazz Day, Culture Night, Haloween, Womens Day, Disabilities Day, LGBT Day<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Accounts For 2024\n<ul class=\"wp-block-list\">\n<li>Full details in the spreadsheet <a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1vRR4_4gqmGxec1lJ6v72u3ONKj-7Lovl1jmhYsSYcBU\/edit?gid=575213617#gid=575213617\" target=\"_blank\" rel=\"noreferrer noopener\">BoyleFilmClub Accounting to 2024<\/a><\/li>\n\n\n\n<li>Breakdown:<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1vRR4_4gqmGxec1lJ6v72u3ONKj-7Lovl1jmhYsSYcBU\/edit?gid=575213617#gid=575213617\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"537\" height=\"679\" src=\"https:\/\/boylefilmclub.ie\/wp-content\/uploads\/2025\/11\/image-1.png\" alt=\"\" class=\"wp-image-698\" style=\"width:435px;height:auto\" srcset=\"https:\/\/boylefilmclub.ie\/wp-content\/uploads\/2025\/11\/image-1.png 537w, https:\/\/boylefilmclub.ie\/wp-content\/uploads\/2025\/11\/image-1-237x300.png 237w, https:\/\/boylefilmclub.ie\/wp-content\/uploads\/2025\/11\/image-1-300x379.png 300w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/a><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\">\n<li>Cross-venue project with Creative Heartlands\n<ul class=\"wp-block-list\">\n<li>Discussion about working closer with other small town venues in the North-West \n<ul class=\"wp-block-list\">\n<li>Common licensing, focussing on rish movies<\/li>\n\n\n\n<li>Syncronizing screening dates<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Membership pricing \n<ul class=\"wp-block-list\">\n<li>Discussion around focussing more on full memberships or on casual single-movie memberships<\/li>\n\n\n\n<li>Decision: Full membership to continue, they are cheap, and partial membership has been available already<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Getting the word out &#8211; Discussion around reaching more audiences\n<ul class=\"wp-block-list\">\n<li>Prepare more leaflets<\/li>\n\n\n\n<li>All members to have access to leaflets to distribute to friends<\/li>\n\n\n\n<li>Send more reminders of upcoming events using existing communications channels<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Investigate an SMS singnup and info service\n<ul class=\"wp-block-list\">\n<li>eg text &#8216;boyle film club&#8217; to 12345 and get the current programme in response<\/li>\n\n\n\n<li>get a reminder on screening days<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>New ideas to investigate\n<ul class=\"wp-block-list\">\n<li>Weekend matinee child-friendly screening<\/li>\n\n\n\n<li>Bringing films to nursing homes<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Movie Suggestions\n<ul class=\"wp-block-list\">\n<li>TBC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Annual General Meeting 2025 21 November &#8211; 7:30PM &#8211; Boyle Family Resource Center<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-682","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/pages\/682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/comments?post=682"}],"version-history":[{"count":15,"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/pages\/682\/revisions"}],"predecessor-version":[{"id":709,"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/pages\/682\/revisions\/709"}],"wp:attachment":[{"href":"https:\/\/boylefilmclub.ie\/index.php\/wp-json\/wp\/v2\/media?parent=682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}